{"id":818062,"date":"2023-07-25T17:48:49","date_gmt":"2023-07-25T09:48:49","guid":{"rendered":"https:\/\/mqmarble.com\/products\/blue-magma-quartzite\/"},"modified":"2023-07-28T17:46:56","modified_gmt":"2023-07-28T09:46:56","slug":"blue-magma-quartzite","status":"publish","type":"products","link":"https:\/\/mqmarble.com\/it\/products\/blue-magma-quartzite\/","title":{"rendered":"Quarzite magmatica blu"},"content":{"rendered":"<p><input type=\"hidden\" id=\"productID\" name=\"productID\" value=\"198909219\" \/><\/p>\n<h3><strong><span style=\"font-size:22px\"><span style=\"line-height:1.6\"><span style=\"font-family:Arial,Helvetica,sans-serif\"><\/span><\/span><\/span><span style=\"line-height:1.8\"><span style=\"font-size:22px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Un capolavoro naturale dal Brasile | Quarzite blu magma <\/span><\/span><\/span><span style=\"font-size:22px\"><span style=\"line-height:1.6\"><span style=\"font-family:Arial,Helvetica,sans-serif\"><\/span><\/span><\/span><\/strong><span style=\"font-size:18px\"><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\">Le lastre di quarzite Blue Magma sono una pietra naturale imponente e di grandi dimensioni che richiede attenzione. La tavolozza dei colori della pietra spazia dal grigio argento freddo al rosso caldo, creando un contrasto accattivante che viene esaltato dalle venature intrecciate di oro, verde e bianco. Questa combinazione di colori e motivi rende ogni lastra di quarzite Blue Magma unica, assicurando che non ci siano due lastre uguali.<\/span><\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/xjojge3m9e_1687681784479.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\"><\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\">Una delle caratteristiche pi\u00f9 impressionanti della quarzite Blue Magma \u00e8 la sua versatilit\u00e0. Questa pietra naturale pu\u00f2 essere utilizzata in una variet\u00e0 di applicazioni, dai pavimenti e dalle pareti ai piani di lavoro della cucina, ai lavabi del bagno e agli spazi esterni. La sua durabilit\u00e0 e resistenza ai graffi, alle macchie e allo sbiadimento ne fanno una scelta ideale per le aree ad alto traffico, rendendola una scelta popolare sia per progetti residenziali che commerciali.<\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\">Una delle caratteristiche pi\u00f9 distintive della quarzite blu magma \u00e8 la sua sorprendente somiglianza con un maestoso incontro di elementi. La sua presenza totalizzante richiama la potenza delle onde dell'oceano, il calore del cielo al tramonto e l'energia grezza del nucleo della terra. I disegni e i colori unici di questa pietra catturano l'essenza del mondo naturale, rendendola la scelta ideale per chi vuole portare la bellezza della natura nelle proprie case e negli spazi commerciali.<\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Le lastre di quarzite Blue Magma sono una scelta popolare per i progetti di decorazione d'interni di alto livello. Questa pietra naturale emana lusso, raffinatezza ed eleganza, rendendola una scelta perfetta per hotel, ristoranti e altri spazi commerciali. I motivi e i colori unici di questa pietra la rendono una scelta eccellente per creare un elemento di spicco, come una parete caratteristica o un pezzo d'accento, che impressioner\u00e0 gli ospiti e lascer\u00e0 un'impressione duratura.<\/span><\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\">Oltre alla sua straordinaria bellezza, le lastre lucidate di quarzite Blue Magma sono anche molto durevoli e resistenti a graffi, macchie e calore. Questa pietra naturale \u00e8 in grado di resistere alle alte temperature, il che la rende una scelta ideale per i piani di lavoro delle cucine, per le cucine all'aperto e per i caminetti. La sua superficie non porosa la rende resistente ai danni dell'acqua, rendendola una scelta ideale per i lavabi del bagno e le pareti delle docce.<\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\">Le lastre di quarzite Blue Magma sono una pietra naturale di prima qualit\u00e0 disponibile in lastre di grandi dimensioni, che facilitano la creazione di installazioni senza soluzione di continuit\u00e0. Le lastre sono disponibili in una variet\u00e0 di spessori, che vanno da 18 a 30 mm, per il taglio di qualsiasi dimensione di piani d'appoggio per abitazioni e progetti di pareti di rappresentanza per immobili commerciali.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h5 class=\"wmkc-blue wmkc-border-blue\">Lussuose lastre di quarzite<\/h5>\n<p>&nbsp;<\/p>\n<table class=\"table\" style=\"width:100%\" cellspacing=\"1\" cellpadding=\"1\" border=\"1\">\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tNome del prodotto\n\t\t\t<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tPietra di lusso Brasile Lastra di quarzite blu magma\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tDimensione\n\t\t\t<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\t3120 x 1770 x 18 mm<br \/>\n\t\t\tSono disponibili anche altre dimensioni<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tFinitura\n\t\t\t<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\t\u00e8 disponibile anche lucidato e levigato.\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tIntroduzione\n\t\t\t<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tBlue Magma Brazilian \u00e8 un fondo grigio chiaro con striature marrone dorato e quarzite esotica estratta in Brasile. Questa pietra \u00e8 particolarmente<br \/>\n\t\t\tper controsoffitti, monumenti, mosaici, pareti esterne e interne e applicazioni a pavimento.\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tTipo di applicazione\n\t\t\t<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n\t\t\tPavimenti, rivestimenti per pareti, piani per lavabi, piani per cucina, piani per panca\n\t\t\t<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h5 class=\"wmkc-blue wmkc-border-blue\">Lastre di lusso in quarzite brasiliana<\/h5>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/z140t08tpo_1687681787605.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p class=\"wmkc-item-title\">Quarzite blu magma<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/ryh1wtjkug_1687681791340.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p class=\"wmkc-item-title\">Lastre di quarzite blu magma<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/0iil5kzbk2_1687681807351.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p class=\"wmkc-item-title\">Lussuosa quarzite magma brasiliana<\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">L'utilizzo delle lastre di quarzite Blue Magma nel vostro progetto di design \u00e8 dovuto alla sua capacit\u00e0 di integrare un'ampia gamma di stili di design. Che preferiate un'estetica contemporanea, tradizionale o eclettica, questa pietra naturale pu\u00f2 essere incorporata nel vostro progetto senza problemi. Per un look contemporaneo, abbinate la quarzite Blue Magma a elementi di design eleganti e minimalisti. Per un look tradizionale, abbinatela a mobili in legno dai toni caldi e a elementi di design tradizionali.<\/span><\/span><\/span><\/p>\n<p><span style=\"line-height:1.8\"><span style=\"font-size:18px\"><span style=\"font-family:Arial,Helvetica,sans-serif\">Le lastre di quarzite brasiliana Blue Magma possono essere rifinite in vari modi per ottenere l'aspetto e la sensazione desiderati. Possono essere lucidate per creare una superficie lucida e riflettente che esalta la bellezza e il colore naturale della pietra. Pu\u00f2 anche essere levigata per creare una finitura opaca che conferisce alla pietra un aspetto pi\u00f9 morbido e discreto. Per una finitura pi\u00f9 tattile, la pietra pu\u00f2 essere sottoposta a una lavorazione a pelle, che le conferisce una superficie strutturata che ne esalta i motivi e i colori naturali.<\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\n<\/p>\n<h5 class=\"wmkc-blue wmkc-border-blue\">Fabbrica di lastre e piani di lavoro in quarzite<\/h5>\n<p>&nbsp;<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/34roa7ymqu_1687681815335.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/vkr6qkmgmk_1687681829890.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/83v7j1gtw1_1687681832357.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/63d66wwdsk_1687681834988.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/r8ncwy7m3z_1687681838336.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/aj9g48utjh_1687681840129.jpg\"  alt=\"Quarzite magmatica blu\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Le lastre di quarzite Blue Magma sono una testimonianza della bellezza naturale e del potere della terra. Questa splendida quarzite proviene dal Brasile ed \u00e8 nota per i suoi modelli unici e ipnotici di grigio-argento, grigio-blu, verde, oro, bianco e rosso caldo. Le venature intrecciate dei colori creano un gioco ipnotico di luci e ombre, rendendola una scelta popolare tra i designer d'interni, gli architetti e i proprietari di case che cercano una pietra unica nel suo genere, in grado di conferire calore, eleganza e raffinatezza a qualsiasi spazio.<\/p>\n<p>Articolo: Quarzite brasiliana Jacaranda di alta qualit\u00e0 con motivo nero e dorato   <br \/>\nMateriale: Quarzite blu magma, quarzite Michelangelo<br \/>\nDimensione: 2400upx1200up, 2600upx1400up, 24 \"x24\", 24 \"x12\", 12 \"x12\" mm<br \/>\nSpessore: 18, 20, 30 mm<br \/>\nSuperficie: Lucidato, levigato, spazzolato, cuoiato<br \/>\nMOQ: 100 SQM<br \/>\nProduttore: Masonry Quality Stone<br \/>\nApplicazione: 100% Quarzite naturale per la facciata del muro, tavolo da pranzo, cucina e bagno controsoffitti per progetti immobiliari.<\/p>","protected":false},"featured_media":552764,"template":"","adweb_product_categories":[106567],"adweb_product_tags":[97382,97379,97380,96291,97383,96294,96999,96293,97381,97384,96292,96295],"class_list":["post-818062","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-quartzite","adweb_product_tag-backsplash-medallion","adweb_product_tag-blue-magma-quartzite","adweb_product_tag-calacatta-nano-stone","adweb_product_tag-china","adweb_product_tag-china-peacock-green-marble-slabs","adweb_product_tag-factory","adweb_product_tag-grey-marble-counter","adweb_product_tag-manufacturers","adweb_product_tag-marble-vanity-top-with-backsplash","adweb_product_tag-quartz-stone-countertop","adweb_product_tag-suppliers","adweb_product_tag-wholesale"],"gallery":[552764,552805,552846,552887,552928],"order":"0","acf":[],"_links":{"self":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_products\/818062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/media\/552764"}],"wp:attachment":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/media?parent=818062"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_product_categories?post=818062"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_product_tags?post=818062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}