{"id":818752,"date":"2023-07-25T18:44:42","date_gmt":"2023-07-25T10:44:42","guid":{"rendered":"https:\/\/mqmarble.com\/products\/polished-brown-granite\/"},"modified":"2023-07-28T18:35:41","modified_gmt":"2023-07-28T10:35:41","slug":"polished-brown-granite","status":"publish","type":"products","link":"https:\/\/mqmarble.com\/it\/products\/polished-brown-granite\/","title":{"rendered":"Granito marrone lucido"},"content":{"rendered":"<p><input type=\"hidden\" id=\"productID\" name=\"productID\" value=\"207607988\" \/><\/p>\n<p><strong>Dettagli del prodotto<\/strong><\/p>\n<p><strong>Granito marrone lucido<\/strong><\/p>\n<p>Questo granito marrone lucido \u00e8 prodotto in Sri Lanka, la perla dell'Oceano Indiano. La sua superficie \u00e8 molto liscia, altamente lucidata e con un effetto specchio ad alta brillantezza. Il granito contiene solitamente cristalli naturali, che vengono lucidati per riflettere la luce e rendere la superficie della pietra brillante, ma \u00e8 necessario mantenere metodi di manutenzione quotidiani per proteggere la sua lucentezza. Questo tipo di granito ha una densit\u00e0 relativamente alta e poche impurit\u00e0, e pu\u00f2 sopportare carichi e pressioni elevati. Pu\u00f2 essere utilizzato come piano di lavoro per pareti esterne di ville e bagni di cucine, ecc. Questo tipo di pietra ha una buona resistenza agli agenti atmosferici e propriet\u00e0 fisiche e meccaniche.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Prodotti aggiuntivi<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/ad6657wawv_1687683152280.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/k4o2a1z7yb_1687683156302.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Parametri del prodotto<\/strong><\/p>\n<table border=\"1\" cellpadding=\"1\" cellspacing=\"1\" style=\"width:100%\" class=\"table\">\n<tbody>\n<tr>\n<td>\n<p>Nome del prodotto<\/p>\n<\/td>\n<td>Piastrelle in pietra naturale a spacco<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\">\n<p>Dimensione<\/p>\n<\/td>\n<td>\n<p>3200*1600 3200*1400<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>3200*1800 3000*1400<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>3000*1500 3000*1600<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>benvenuto alle dimensioni personalizzate<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Spessore<\/p>\n<\/td>\n<td>\n<p>12 mm 15 mm 18 mm 20 mm 30 mm<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Colore<\/p>\n<\/td>\n<td>\n<p>Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Imballaggio<\/p>\n<\/td>\n<td>\n<p>Fasci di legno, casse di legno e casse di legno con certificato di fumigazione, casse di compensato ecc. per soddisfare il requisito di una perfetta protezione dei prodotti in pietra<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p>Tempi di consegna<\/p>\n<\/td>\n<td>\n<p>entro 10-15 giorni dalla ricezione del deposito 30%<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>FAQ<\/strong><\/p>\n<p>D: Quali sono i tempi di realizzazione dei campioni?<\/p>\n<p>R: Di solito impieghiamo 3-5 giorni per realizzare i campioni.<\/p>\n<p>&nbsp;<\/p>\n<p>D: Qual \u00e8 il vostro MOQ?<\/p>\n<p>R: Il nostro MOQ \u00e8 solitamente di 100 metri quadrati.<\/p>\n<p>&nbsp;<\/p>\n<p>D: Quali sono i tempi di consegna?<\/p>\n<p>R: Il tempo di consegna \u00e8 di 10 giorni dopo aver ricevuto il deposito.<\/p>\n<p>&nbsp;<\/p>\n<p>D: Qual \u00e8 il porto di spedizione?<\/p>\n<p>A: Spediamo le merci via il porto di Xiamen anche pu\u00f2 essere qualsiasi porto della Cina<\/p>\n<p>&nbsp;<\/p>\n<p>Q. Dove si trova il vostro stabilimento? Come posso visitarvi?<br \/>\nLa nostra fabbrica si trova a Shuitou Town, il pi\u00f9 grande mercato di pietra naturale del mondo. Si prega di raggiungere l'aeroporto internazionale di Xiamen o Jinjiang, vi verremo a prendere l\u00ec. Siete sempre i benvenuti!<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/nc2te8x51b_1687683158533.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/7ybv7sef0t_1687683160784.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/g81x040f62_1687683162589.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/6ntt6jmrj2_1687683165031.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/4kuo5tnhoj_1687683168872.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/mqmarble.com\/wp-content\/uploads\/2025\/06\/stbngu9tsl_1687683170563.jpg\"  alt=\"Granito marrone lucido\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Materiale: granito marrone grasso <br \/>\nOrigine: Sri Lanka <br \/>\nDimensioni: 120 x 90 x 2 cm o personalizzate. <br \/> <br \/>\nFinito: Lucidato, levigato, ecc.<br \/> <br \/>\nApplicazioni: applicazioni a parete e a pavimento, piani d'appoggio, piscine e <br \/>\nrivestimenti di pareti, davanzali di finestre e altri progetti di design<\/p>","protected":false},"featured_media":593481,"template":"","adweb_product_categories":[110949,110952],"adweb_product_tags":[98076,96291,97653,96294,98075,96293,98073,96683,98074,96292,97741,96295],"class_list":["post-818752","products","type-products","status-publish","has-post-thumbnail","hentry","adweb_product_cat-granite","adweb_product_cat-imported-granite","adweb_product_tag-black-marble-with-white-veins","adweb_product_tag-china","adweb_product_tag-daltile-medallions","adweb_product_tag-factory","adweb_product_tag-golden-peach-granite","adweb_product_tag-manufacturers","adweb_product_tag-polished-brown-granite","adweb_product_tag-polished-carrara-white-marbles","adweb_product_tag-sealing-quartz-countertops","adweb_product_tag-suppliers","adweb_product_tag-white-and-grey-marble","adweb_product_tag-wholesale"],"gallery":[593481,593522,593563,593604],"order":"0","acf":[],"_links":{"self":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_products\/818752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_products"}],"about":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/media\/593481"}],"wp:attachment":[{"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/media?parent=818752"}],"wp:term":[{"taxonomy":"adweb_product_cat","embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_product_categories?post=818752"},{"taxonomy":"adweb_product_tag","embeddable":true,"href":"https:\/\/mqmarble.com\/it\/wp-json\/wp\/v2\/adweb_product_tags?post=818752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}